{"id":10441,"date":"2025-01-27T09:09:49","date_gmt":"2025-01-27T09:09:49","guid":{"rendered":"https:\/\/cemestone.com\/?post_type=product&#038;p=10441"},"modified":"2025-02-13T01:31:07","modified_gmt":"2025-02-13T01:31:07","slug":"%d8%a7%d8%b3%d9%85%d9%86%d8%aa-%d8%a7%d9%84%d9%85%d8%aa%d8%ad%d8%af%d8%a9-%d8%a7%d8%b3%d9%85%d9%86%d8%aa-%d8%a8%d9%88%d8%b1%d8%aa%d9%84%d8%a7%d9%86%d8%af%d9%8a-%d8%b9%d8%a7%d8%af%d9%8a-%d9%85","status":"publish","type":"product","link":"https:\/\/cemestone.com\/ar\/product\/%d8%a7%d8%b3%d9%85%d9%86%d8%aa-%d8%a7%d9%84%d9%85%d8%aa%d8%ad%d8%af%d8%a9-%d8%a7%d8%b3%d9%85%d9%86%d8%aa-%d8%a8%d9%88%d8%b1%d8%aa%d9%84%d8%a7%d9%86%d8%af%d9%8a-%d8%b9%d8%a7%d8%af%d9%8a-%d9%85\/","title":{"rendered":"\u0627\u0633\u0645\u0646\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629 &#8211; \u0627\u0633\u0645\u0646\u062a \u0628\u0648\u0631\u062a\u0644\u0627\u0646\u062f\u064a \u0639\u0627\u062f\u064a &#8211; \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a &#8211; 50\u0643"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0627\u0633\u0645\u0646\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629 &#8211; \u0627\u0633\u0645\u0646\u062a \u0628\u0648\u0631\u062a\u0644\u0627\u0646\u062f\u064a \u0639\u0627\u062f\u064a &#8211; \u0645\u062a\u0639\u062f\u062f \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645\u0627\u062a &#8211; 50\u0643<br \/>\n\u0635\u0646\u0627\u0639\u0629 \u0633\u0639\u0648\u062f\u064a\u0629<\/p>\n","protected":false},"featured_media":10525,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[333,327],"product_tag":[],"class_list":{"0":"post-10441","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-opc-ar","7":"product_cat-327","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple","14":"add-to-wishlist-after_add_to_cart"},"_links":{"self":[{"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/product\/10441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/comments?post=10441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/media\/10525"}],"wp:attachment":[{"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/media?parent=10441"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/product_brand?post=10441"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/product_cat?post=10441"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cemestone.com\/ar\/wp-json\/wp\/v2\/product_tag?post=10441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}